{"id":617,"date":"2019-02-14T13:10:11","date_gmt":"2019-02-14T12:10:11","guid":{"rendered":"http:\/\/produire-en-nouvelle-aquitaine.org\/?p=617"},"modified":"2019-02-15T16:25:41","modified_gmt":"2019-02-15T15:25:41","slug":"permis-de-construire-de-colas-devauchelle","status":"publish","type":"post","link":"https:\/\/produire-en-nouvelle-aquitaine.org\/index.php\/2019\/02\/14\/permis-de-construire-de-colas-devauchelle\/","title":{"rendered":"Permis de construire de Colas Devauchelle"},"content":{"rendered":"<p class=\"p1\"><span class=\"s1\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-618\" src=\"http:\/\/produire-en-nouvelle-aquitaine.org\/wp-content\/uploads\/2019\/02\/Capture-d\u2019e\u0301cran-2019-02-14-a\u0300-13.09.06-300x169.png\" alt=\"\" width=\"300\" height=\"169\" srcset=\"https:\/\/produire-en-nouvelle-aquitaine.org\/wp-content\/uploads\/2019\/02\/Capture-d\u2019e\u0301cran-2019-02-14-a\u0300-13.09.06-300x169.png 300w, https:\/\/produire-en-nouvelle-aquitaine.org\/wp-content\/uploads\/2019\/02\/Capture-d\u2019e\u0301cran-2019-02-14-a\u0300-13.09.06.png 380w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">Profitez de deux occasions de voir ou revoir <b>Permis de Construire <\/b>de\u00a0Colas Devauchelle \u00e0 Toulouse :<\/span><\/p>\n<ul>\n<li class=\"p1\"><span class=\"s1\">dimanche 17 mars en soir\u00e9e au Caf\u00e9 Itin\u00e9raire Bis \u00e0 Toulouse \u00a0(31)<\/span><\/li>\n<li class=\"p1\"><span class=\"s1\">dimanche 7 avril \u00e0 11hH00 \u00e0 l\u2019American Cosmographe de Toulouse (31)<\/span><\/li>\n<\/ul>\n<p><span class=\"s1\"><b>Permis de Construire<\/b> est un documentaire (<\/span>78&prime;) qui propose d&rsquo;explorer l&rsquo;id\u00e9e d&rsquo;habiter autrement, en suivant le parcours atypique du r\u00e9alisateur lui-m\u00eame, exp\u00e9rimentateur avide de libert\u00e9,\u00a0 depuis sa premi\u00e8re colocation jusqu&rsquo;\u00e0 l&rsquo;autoconstruction de sa maison, aventure collective dans un coin de campagne recul\u00e9.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone  wp-image-665\" src=\"http:\/\/produire-en-nouvelle-aquitaine.org\/wp-content\/uploads\/2019\/02\/1C2D2611-85AD-46F3-9CDC-8242EF290C74-212x300.jpeg\" alt=\"\" width=\"115\" height=\"163\" srcset=\"https:\/\/produire-en-nouvelle-aquitaine.org\/wp-content\/uploads\/2019\/02\/1C2D2611-85AD-46F3-9CDC-8242EF290C74-212x300.jpeg 212w, https:\/\/produire-en-nouvelle-aquitaine.org\/wp-content\/uploads\/2019\/02\/1C2D2611-85AD-46F3-9CDC-8242EF290C74-768x1086.jpeg 768w, https:\/\/produire-en-nouvelle-aquitaine.org\/wp-content\/uploads\/2019\/02\/1C2D2611-85AD-46F3-9CDC-8242EF290C74-724x1024.jpeg 724w, https:\/\/produire-en-nouvelle-aquitaine.org\/wp-content\/uploads\/2019\/02\/1C2D2611-85AD-46F3-9CDC-8242EF290C74-1320x1867.jpeg 1320w, https:\/\/produire-en-nouvelle-aquitaine.org\/wp-content\/uploads\/2019\/02\/1C2D2611-85AD-46F3-9CDC-8242EF290C74.jpeg 1800w\" sizes=\"(max-width: 115px) 100vw, 115px\" \/>\u00a0 Bande annonce <a href=\"https:\/\/vimeo.com\/239803315\">l\u00e0 !\u00a0\u00a0<\/a><\/p>\n<p>Avec le soutien de la R\u00e9gion Nouvelle-Aquitaine, la fondation Abb\u00e9-Pierre, la ville de N\u00e9rac et 154 souscripteurs.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Profitez de deux occasions de voir ou revoir Permis de Construire de\u00a0Colas Devauchelle \u00e0 Toulouse : dimanche 17 mars en soir\u00e9e au Caf\u00e9 Itin\u00e9raire Bis \u00e0 Toulouse \u00a0(31) dimanche 7 avril \u00e0 11hH00 \u00e0 l\u2019American Cosmographe de Toulouse (31) Permis de Construire est un documentaire (78&prime;) qui propose d&rsquo;explorer l&rsquo;id\u00e9e d&rsquo;habiter autrement, en suivant le&hellip; <a href=\"https:\/\/produire-en-nouvelle-aquitaine.org\/index.php\/2019\/02\/14\/permis-de-construire-de-colas-devauchelle\/\" class=\"more-link\">Lire la suite <span class=\"screen-reader-text\">Permis de construire de Colas Devauchelle<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"_links":{"self":[{"href":"https:\/\/produire-en-nouvelle-aquitaine.org\/index.php\/wp-json\/wp\/v2\/posts\/617"}],"collection":[{"href":"https:\/\/produire-en-nouvelle-aquitaine.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/produire-en-nouvelle-aquitaine.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/produire-en-nouvelle-aquitaine.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/produire-en-nouvelle-aquitaine.org\/index.php\/wp-json\/wp\/v2\/comments?post=617"}],"version-history":[{"count":3,"href":"https:\/\/produire-en-nouvelle-aquitaine.org\/index.php\/wp-json\/wp\/v2\/posts\/617\/revisions"}],"predecessor-version":[{"id":667,"href":"https:\/\/produire-en-nouvelle-aquitaine.org\/index.php\/wp-json\/wp\/v2\/posts\/617\/revisions\/667"}],"wp:attachment":[{"href":"https:\/\/produire-en-nouvelle-aquitaine.org\/index.php\/wp-json\/wp\/v2\/media?parent=617"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/produire-en-nouvelle-aquitaine.org\/index.php\/wp-json\/wp\/v2\/categories?post=617"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/produire-en-nouvelle-aquitaine.org\/index.php\/wp-json\/wp\/v2\/tags?post=617"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}